{"id":240,"count":0,"description":"","link":"http:\/\/www.ee-ya.com\/blog\/tag\/aquarium-pressure-regulator-412a-363a97\/","name":"Aquarium Pressure Regulator","slug":"aquarium-pressure-regulator-412a-363a97","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"http:\/\/www.ee-ya.com\/blog\/wp-json\/wp\/v2\/tags\/240","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.ee-ya.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"http:\/\/www.ee-ya.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"http:\/\/www.ee-ya.com\/blog\/wp-json\/wp\/v2\/posts?tags=240"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}